{"id":3443,"date":"2021-05-28T15:36:16","date_gmt":"2021-05-28T13:36:16","guid":{"rendered":"https:\/\/i-toile.com\/?p=3443"},"modified":"2021-06-16T11:29:07","modified_gmt":"2021-06-16T09:29:07","slug":"augmentez-votre-visibilite-grace-aux-subventions","status":"publish","type":"post","link":"https:\/\/i-toile.com\/en\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/","title":{"rendered":"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions !"},"content":{"rendered":"<p>Afin d\u2019augmenter sa visibilit\u00e9 et d\u2019accro\u00eetre son chiffre d\u2019affaires, il est naturel de se tourner vers le<br>digital et quoi de mieux que de cr\u00e9er son site internet 100% personnalis\u00e9 \u00e0 l\u2019image de votre<br>entreprise et de promouvoir son entreprise \u00e0 travers des phots et vid\u00e9os qui sont en total ad\u00e9quation avec votre image.<br>Le besoin se fait d\u2019autant plus ressentir car la crise sanitaire du Covid-19 limite le commerce<br>traditionnel et nous pousse vers le num\u00e9rique. Le site internet devient alors indispensable \u00e0 la<br>p\u00e9rennit\u00e9 des entreprises.<br>La question du financement de la digitalisation se pose, alors que la tr\u00e9sorerie des entreprises n\u2019est<br>pas au meilleure de sa forme. Pour certaines entreprises le site internet est un r\u00e9el investissement<br>tandis que d\u2019autre ne peuvent l\u2019envisager car elles ne peuvent pas se le payer.<br>I-Toile a donc s\u00e9lectionner pour vous des subventions qui pourraient vous donner un coup de pouce<br>dans votre d\u00e9cision\u00a0:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les subventions sp\u00e9cifiques pour l\u2019aide \u00e0 la cr\u00e9ation d\u2019un site<br>internet et des photos et vid\u00e9os promotionnels\u00a0:<\/h2>\n\n\n\n<p>Pour le gouvernement la num\u00e9risation des commerces est un enjeu absolu. Un commerce sur trois<br>est d\u00e9j\u00e0 digitalis\u00e9 et l\u2019Elys\u00e9e compte bien accro\u00eetre ce taux. C\u2019est pourquoi une subvention de <strong>500<\/strong><br>euros est disponible pour les TPE\/PME de moins de 11 salari\u00e9s, ayant un chiffre d\u2019affaires inf\u00e9rieur \u00e0<br>2 millions d\u2019euros HT annuel et qui ont ferm\u00e9s durant la pand\u00e9mie.<\/p>\n\n\n\n<p><br>Cette subvention est<strong> disponible jusqu\u2019au 30 juin<\/strong> alors ne laissez pas passer votre chance.<br>Un petit coup de pouce non n\u00e9gligeable m\u00eame s\u2019il ne finance qu\u2019une partie du projet web.<br><\/p>\n\n\n\n<p>Vous retrouverez l\u2019ensemble des d\u00e9tails sur <a href=\"https:\/\/www.economie.gouv.fr\/plan-de-relance\/profils\/entreprises\/aides-francenum-transformation-numerique\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.economie.gouv.fr\/plan-de-<br>relance\/profils\/entreprises\/aides-francenum-transformation-numerique<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" sizes=\"(max-width: 683px) 100vw, 683px\" src=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-683x1024.jpg\" alt=\"cr\u00e9ation de site web\" class=\"wp-image-1993\" srcset=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-683x1024.jpg 683w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-600x900.jpg 600w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-200x300.jpg 200w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-768x1152.jpg 768w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-1024x1536.jpg 1024w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-1366x2048.jpg 1366w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg 1707w\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les aides des r\u00e9gions pour la digitalisation de votre entreprise :<\/h2>\n\n\n\n<p>Au-del\u00e0 de ces 500 euros subventionn\u00e9s par l\u2019Etat, certaines r\u00e9gions soutiennent la transition<br>num\u00e9rique en finan\u00e7ant les entreprises. Il faut donc se renseigner aupr\u00e8s des collectivit\u00e9s r\u00e9gionales<br>afin de savoir si vous \u00eates \u00e9ligible \u00e0 ces aides ou non. Ces aides sont cumulables en plus des 500<br>euros subventionn\u00e9s par l\u2019Etat.<\/p>\n\n\n\n<p>Pour la r\u00e9gion PACA, un ch\u00e8que de r\u00e9ouverture est disponible pour les \u00e9tablissements \u00e9ligibles&nbsp;:<br><a href=\"https:\/\/wecomm.fr\/aides-covid\/cheque-reouverture-paca\/#:~:text=r%C3%A9ouverture%20en%20PACA.-,Qu'est%2Dce%20que%20le%20ch%C3%A8que%20r%C3%A9ouverture%20%3F,d'activit%C3%A9s%20importants%20sont%20touch%C3%A9s.\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/wecomm.fr\/aides-covid\/cheque-reouverture-<br>paca\/#:~:text=r%C3%A9ouverture%20en%20PACA.-<br>,Qu&rsquo;est%2Dce%20que%20le%20ch%C3%A8que%20r%C3%A9ouverture%20%3F,d&rsquo;activit%C3%A9s%2<br>0importants%20sont%20touch%C3%A9s.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"941\" height=\"597\" src=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/05\/Ordi-site-ITOILE-1.png\" alt=\"\" class=\"wp-image-3446\" srcset=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/05\/Ordi-site-ITOILE-1.png 941w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/05\/Ordi-site-ITOILE-1-600x381.png 600w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/05\/Ordi-site-ITOILE-1-300x190.png 300w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/05\/Ordi-site-ITOILE-1-768x487.png 768w\" sizes=\"(max-width: 941px) 100vw, 941px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les accompagnements pour aider \u00e0 la num\u00e9risation des<br>entreprises.<\/h2>\n\n\n\n<p>Dans quelle mesure mon entreprise n\u00e9cessite un site web&nbsp;? Quels sont mes objectifs&nbsp;? Comment<br>gagner du temps dans mes process gr\u00e2ce \u00e0 internet&nbsp;? Afin de r\u00e9pondre \u00e0 ces questions et d\u2019identifier<br>pr\u00e9cis\u00e9ment les besoins de votre entreprise (site vitrine, e-commerce \u2026) vous pouvez faire appel<br>\u00e0&nbsp;France Num.<br>Cette plateforme vous permettra de tester votre maturit\u00e9 num\u00e9rique, mais \u00e9galement de trouver un<br>expert num\u00e9rique dans votre r\u00e9gion. Ces experts peuvent \u00eatre publics ou priv\u00e9s.&nbsp;L\u2019accompagnement<br>des TPE\/PME est leur sp\u00e9cialit\u00e9.<br>La R\u00e9gion Sud met \u00e0 la disposition des entreprises accompagn\u00e9es de consultants experts sur un large<br>spectre de th\u00e9matiques num\u00e9riques li\u00e9es au contexte de crise :<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Webmarketing, communication, pr\u00e9sence en ligne<\/em> : communication de crise et comment garder le contact avec sa client\u00e8le gr\u00e2ce aux r\u00e9seaux sociaux, basculer en e-commerce et booster ses ventes en ligne lorsque le point de vente est ferm\u00e9, prendre le temps de monter son site internet et cr\u00e9er du contenu<\/li><li> <em>Cybers\u00e9curit\u00e9<\/em> : Assistance aux entreprises victimes de cyber-attaque, s\u00e9curisation de mani\u00e8re ordonn\u00e9e de la mise en t\u00e9l\u00e9travail des collaborateurs, conseil strat\u00e9gique en cybers\u00e9curit\u00e9.<\/li><li><em>Outils m\u00e9tiers et collaboratifs <\/em>: communication entre les collaborateurs, gestion de contacts et de suivi des interactions \u00e0 distance, partage, stockage, transfert de documents, gestion de projet pour s\u2019organiser : r\u00e9partition des t\u00e2ches, suivi de l\u2019avancement, num\u00e9risation, bureautique, simulation de tr\u00e9sorerie. Mais aussi un large \u00e9ventail de prestation pour pr\u00e9parer la sortie de crise sur toutes les th\u00e9matiques num\u00e9riques.<\/li><\/ul>\n\n\n\n<p>D\u2019autre formations gratuites sont \u00e9galement disponibles et vous aiderons \u00e0 mieux comprendre et<br>appr\u00e9hender l\u2019enjeu de la num\u00e9risation de votre entreprise&nbsp;: <a href=\"https:\/\/www.fun-mooc.fr\/fr\/cours\/ma-tpe-rendez-vous-avec-le-numerique\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.fun-mooc.fr\/fr\/cours\/ma-<br>tpe-rendez-vous-avec-le-numerique\/<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"477\" sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2-1024x477.png\" alt=\"gestion reseaux sociaux\" class=\"wp-image-1718\" srcset=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2-1024x477.png 1024w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2-600x280.png 600w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2-300x140.png 300w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2-768x358.png 768w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2-1536x716.png 1536w, https:\/\/i-toile.com\/wp-content\/uploads\/2021\/03\/2021-03-29-2.png 1909w\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><em>I-TOILE peut r\u00e9aliser <strong>tous<\/strong> vos projets afin de vous offrir une meilleure visibilit\u00e9, pour tous renseignements n&rsquo;h\u00e9sitez pas \u00e0 nous contacter ou \u00e0 prendre rendez-vous ! <\/em><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link\" href=\"https:\/\/i-toile.com\/en\/prestations-produits\/creation-de-site-web\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-black-color\">Cliquez ici pour d\u00e9couvrir nos offres<\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link\" href=\"\" target=\"_blank\" rel=\"noreferrer noopener\">cliquez ici pour voir nos r\u00e9alisations<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le ch\u00e8que num\u00e9rique vous aide \u00e0 cr\u00e9er votre site internet et \u00e0 g\u00e9n\u00e9rer du contenu photos et vid\u00e9os.<\/p>","protected":false},"author":2,"featured_media":1993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8,7],"tags":[],"class_list":["post-3443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio-visuel","category-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions ! Web - Fabricant de mobilier digitaux<\/title>\n<meta name=\"description\" content=\"Info COVID - L&#039;accroissement de la visibilit\u00e9 et du CA passe par le digital. L&#039;\u00e9tat vous subventionne alors cr\u00e9ez votre site internet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/i-toile.com\/en\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions ! Web - Fabricant de mobilier digitaux\" \/>\n<meta property=\"og:description\" content=\"Info COVID - L&#039;accroissement de la visibilit\u00e9 et du CA passe par le digital. L&#039;\u00e9tat vous subventionne alors cr\u00e9ez votre site internet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/i-toile.com\/en\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/\" \/>\n<meta property=\"og:site_name\" content=\"Fabricant de mobilier digitaux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itoile.communication.agence\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-28T13:36:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-16T09:29:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"I-TOILE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"I-TOILE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/\"},\"author\":{\"name\":\"I-TOILE\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/#\\\/schema\\\/person\\\/bc84720e8f8200dde1c96a990e17c08f\"},\"headline\":\"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions !\",\"datePublished\":\"2021-05-28T13:36:16+00:00\",\"dateModified\":\"2021-06-16T09:29:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/\"},\"wordCount\":775,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i-toile.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/pexels-djordje-petrovic-2102416-scaled.jpg\",\"articleSection\":[\"Audio visuel\",\"Web\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/\",\"url\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/\",\"name\":\"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions ! Web - Fabricant de mobilier digitaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i-toile.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/pexels-djordje-petrovic-2102416-scaled.jpg\",\"datePublished\":\"2021-05-28T13:36:16+00:00\",\"dateModified\":\"2021-06-16T09:29:07+00:00\",\"description\":\"Info COVID - L'accroissement de la visibilit\u00e9 et du CA passe par le digital. L'\u00e9tat vous subventionne alors cr\u00e9ez votre site internet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i-toile.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/pexels-djordje-petrovic-2102416-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/i-toile.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/pexels-djordje-petrovic-2102416-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"cr\u00e9ation de site web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/blog\\\/web\\\/augmentez-votre-visibilite-grace-aux-subventions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/i-toile.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/#website\",\"url\":\"https:\\\/\\\/i-toile.com\\\/\",\"name\":\"Fabricant de mobilier digitaux\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/i-toile.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/#organization\",\"name\":\"Fabricant de mobilier digitaux\",\"url\":\"https:\\\/\\\/i-toile.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i-toile.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-cropped-logo-fluo-fond-transparant-4.png\",\"contentUrl\":\"https:\\\/\\\/i-toile.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-cropped-logo-fluo-fond-transparant-4.png\",\"width\":1998,\"height\":1152,\"caption\":\"Fabricant de mobilier digitaux\"},\"image\":{\"@id\":\"https:\\\/\\\/i-toile.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itoile.communication.agence\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/i-toile-digital-signage\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/i-toile.com\\\/#\\\/schema\\\/person\\\/bc84720e8f8200dde1c96a990e17c08f\",\"name\":\"I-TOILE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56c29fb53b657faacddb86cfe20c117151541b7259e558c6794cabd3df30c09f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56c29fb53b657faacddb86cfe20c117151541b7259e558c6794cabd3df30c09f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56c29fb53b657faacddb86cfe20c117151541b7259e558c6794cabd3df30c09f?s=96&d=mm&r=g\",\"caption\":\"I-TOILE\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/i-toile-fr\\\/\"],\"url\":\"https:\\\/\\\/i-toile.com\\\/en\\\/blog\\\/author\\\/itoile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions ! Web - Fabricant de mobilier digitaux","description":"Info COVID - L'accroissement de la visibilit\u00e9 et du CA passe par le digital. L'\u00e9tat vous subventionne alors cr\u00e9ez votre site internet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/i-toile.com\/en\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/","og_locale":"en_GB","og_type":"article","og_title":"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions ! Web - Fabricant de mobilier digitaux","og_description":"Info COVID - L'accroissement de la visibilit\u00e9 et du CA passe par le digital. L'\u00e9tat vous subventionne alors cr\u00e9ez votre site internet.","og_url":"https:\/\/i-toile.com\/en\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/","og_site_name":"Fabricant de mobilier digitaux","article_publisher":"https:\/\/www.facebook.com\/itoile.communication.agence\/","article_published_time":"2021-05-28T13:36:16+00:00","article_modified_time":"2021-06-16T09:29:07+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg","type":"image\/jpeg"}],"author":"I-TOILE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"I-TOILE","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#article","isPartOf":{"@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/"},"author":{"name":"I-TOILE","@id":"https:\/\/i-toile.com\/#\/schema\/person\/bc84720e8f8200dde1c96a990e17c08f"},"headline":"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions !","datePublished":"2021-05-28T13:36:16+00:00","dateModified":"2021-06-16T09:29:07+00:00","mainEntityOfPage":{"@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/"},"wordCount":775,"commentCount":0,"publisher":{"@id":"https:\/\/i-toile.com\/#organization"},"image":{"@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#primaryimage"},"thumbnailUrl":"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg","articleSection":["Audio visuel","Web"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/","url":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/","name":"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions ! Web - Fabricant de mobilier digitaux","isPartOf":{"@id":"https:\/\/i-toile.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#primaryimage"},"image":{"@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#primaryimage"},"thumbnailUrl":"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg","datePublished":"2021-05-28T13:36:16+00:00","dateModified":"2021-06-16T09:29:07+00:00","description":"Info COVID - L'accroissement de la visibilit\u00e9 et du CA passe par le digital. L'\u00e9tat vous subventionne alors cr\u00e9ez votre site internet.","breadcrumb":{"@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#primaryimage","url":"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg","contentUrl":"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg","width":1707,"height":2560,"caption":"cr\u00e9ation de site web"},{"@type":"BreadcrumbList","@id":"https:\/\/i-toile.com\/blog\/web\/augmentez-votre-visibilite-grace-aux-subventions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/i-toile.com\/"},{"@type":"ListItem","position":2,"name":"Augmentez votre visibilit\u00e9 gr\u00e2ce aux subventions !"}]},{"@type":"WebSite","@id":"https:\/\/i-toile.com\/#website","url":"https:\/\/i-toile.com\/","name":"Fabricant de mobilier digitaux","description":"","publisher":{"@id":"https:\/\/i-toile.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/i-toile.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/i-toile.com\/#organization","name":"Fabricant de mobilier digitaux","url":"https:\/\/i-toile.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/i-toile.com\/#\/schema\/logo\/image\/","url":"https:\/\/i-toile.com\/wp-content\/uploads\/2022\/07\/cropped-cropped-logo-fluo-fond-transparant-4.png","contentUrl":"https:\/\/i-toile.com\/wp-content\/uploads\/2022\/07\/cropped-cropped-logo-fluo-fond-transparant-4.png","width":1998,"height":1152,"caption":"Fabricant de mobilier digitaux"},"image":{"@id":"https:\/\/i-toile.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/itoile.communication.agence\/","https:\/\/www.linkedin.com\/company\/i-toile-digital-signage"]},{"@type":"Person","@id":"https:\/\/i-toile.com\/#\/schema\/person\/bc84720e8f8200dde1c96a990e17c08f","name":"I-TOILE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/56c29fb53b657faacddb86cfe20c117151541b7259e558c6794cabd3df30c09f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56c29fb53b657faacddb86cfe20c117151541b7259e558c6794cabd3df30c09f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56c29fb53b657faacddb86cfe20c117151541b7259e558c6794cabd3df30c09f?s=96&d=mm&r=g","caption":"I-TOILE"},"sameAs":["https:\/\/www.linkedin.com\/company\/i-toile-fr\/"],"url":"https:\/\/i-toile.com\/en\/blog\/author\/itoile\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg",1707,2560,false],"thumbnail":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-150x150.jpg",150,150,true],"medium":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-200x300.jpg",200,300,true],"medium_large":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-768x1152.jpg",768,1152,true],"large":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-683x1024.jpg",683,1024,true],"1536x1536":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-1024x1536.jpg",1024,1536,true],"2048x2048":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-1366x2048.jpg",1366,2048,true],"trp-custom-language-flag":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg",8,12,false],"woocommerce_thumbnail":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-600x900.jpg",600,900,true],"woocommerce_gallery_thumbnail":["https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"I-TOILE","author_link":"https:\/\/i-toile.com\/en\/blog\/author\/itoile\/"},"uagb_comment_info":15,"uagb_excerpt":"Le ch\u00e8que num\u00e9rique vous aide \u00e0 cr\u00e9er votre site internet et \u00e0 g\u00e9n\u00e9rer du contenu photos et vid\u00e9os.","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i-toile.com\/wp-content\/uploads\/2021\/04\/pexels-djordje-petrovic-2102416-scaled.jpg","_links":{"self":[{"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/posts\/3443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/comments?post=3443"}],"version-history":[{"count":5,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/posts\/3443\/revisions"}],"predecessor-version":[{"id":3522,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/posts\/3443\/revisions\/3522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/media\/1993"}],"wp:attachment":[{"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/media?parent=3443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/categories?post=3443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/i-toile.com\/en\/wp-json\/wp\/v2\/tags?post=3443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}